{"id":454,"date":"2023-07-03T15:08:31","date_gmt":"2023-07-03T15:08:31","guid":{"rendered":"https:\/\/ummahhealthcare.com.my\/?page_id=454"},"modified":"2023-10-09T02:46:29","modified_gmt":"2023-10-09T02:46:29","slug":"treatments-procedures","status":"publish","type":"page","link":"https:\/\/ummahhealthcare.com.my\/ms_my\/our-services\/treatments-procedures\/","title":{"rendered":"2 &#8211; Treatments &#038; Procedures"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"454\" class=\"elementor elementor-454\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3cf324ef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3cf324ef\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1c7b67b\" data-id=\"1c7b67b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ae580d5 elementor-widget elementor-widget-heading\" data-id=\"6ae580d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Pith0s<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-390800e5 elementor-widget__width-initial elementor-widget elementor-widget-elementskit-heading\" data-id=\"390800e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\"><h1 class=\"ekit-heading--title elementskit-section-title \">Treatments &amp; Procedures<\/h1><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6df6791c elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6df6791c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Service<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Treatments &amp; Procedures<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15c4c066 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15c4c066\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4f97a9eb\" data-id=\"4f97a9eb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2c9ae598 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c9ae598\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-72a9d22e\" data-id=\"72a9d22e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4cabd1b elementor-widget elementor-widget-image\" data-id=\"4cabd1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"710\" height=\"758\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-31-45.jpg\" class=\"attachment-large size-large wp-image-1833\" alt=\"\" srcset=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-31-45.jpg 710w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-31-45-281x300.jpg 281w\" sizes=\"(max-width: 710px) 100vw, 710px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2048fc1 elementor-widget elementor-widget-spacer\" data-id=\"2048fc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27be4e01 elementor-widget elementor-widget-heading\" data-id=\"27be4e01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Nebulizer<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68eb9460 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"68eb9460\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Inhalation therapy<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Respiratory care<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b44e7d elementor-widget elementor-widget-text-editor\" data-id=\"2b44e7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table><tbody><tr><td>Effective respiratory treatment through inhalation therapy<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a0895e6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4a0895e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fd3eefe elementor-widget elementor-widget-button\" data-id=\"7fd3eefe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-wobble-horizontal\" href=\"https:\/\/ummahhealthcare.com.my\/our-services\/consultation\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-524e481\" data-id=\"524e481\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f0299f1 elementor-widget elementor-widget-image\" data-id=\"f0299f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"712\" height=\"712\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-33-57.jpg\" class=\"attachment-large size-large wp-image-1832\" alt=\"\" srcset=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-33-57.jpg 712w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-33-57-300x300.jpg 300w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-33-57-150x150.jpg 150w\" sizes=\"(max-width: 712px) 100vw, 712px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a37df1 elementor-widget elementor-widget-spacer\" data-id=\"2a37df1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b64eaed elementor-widget elementor-widget-heading\" data-id=\"b64eaed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Dressing<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df6dc68 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"df6dc68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Wound care<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Bandage application<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26e3a09 elementor-widget elementor-widget-text-editor\" data-id=\"26e3a09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table><tbody><tr><td>Proper wound care through dressing and bandage application<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e465de3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"e465de3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43dd2b0 elementor-widget elementor-widget-button\" data-id=\"43dd2b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-wobble-horizontal\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e560b81\" data-id=\"e560b81\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f615fd6 elementor-widget elementor-widget-image\" data-id=\"f615fd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"585\" height=\"316\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/wax-removal.png\" class=\"attachment-large size-large wp-image-1831\" alt=\"\" srcset=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/wax-removal.png 585w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/wax-removal-300x162.png 300w\" sizes=\"(max-width: 585px) 100vw, 585px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4dda3cb elementor-widget elementor-widget-spacer\" data-id=\"4dda3cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9dc2f44 elementor-widget elementor-widget-heading\" data-id=\"9dc2f44\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ear Cleaning<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1eed0e elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"a1eed0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ear wax removal<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ear hygiene<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62411cb elementor-widget elementor-widget-text-editor\" data-id=\"62411cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table><tbody><tr><td>Thorough cleaning and removal of ear wax for ear hygiene<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c43f3c0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c43f3c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8c8ccf elementor-widget elementor-widget-button\" data-id=\"d8c8ccf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-wobble-horizontal\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7443778 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7443778\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-41742b7\" data-id=\"41742b7\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47aced0 elementor-widget elementor-widget-image\" data-id=\"47aced0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"670\" height=\"670\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-38-17.jpg\" class=\"attachment-large size-large wp-image-1830\" alt=\"\" srcset=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-38-17.jpg 670w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-38-17-300x300.jpg 300w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-38-17-150x150.jpg 150w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f823e9f elementor-widget elementor-widget-spacer\" data-id=\"f823e9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7b8e23 elementor-widget elementor-widget-heading\" data-id=\"a7b8e23\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Phlegm Suction (Sedut Kahak)<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6b567d elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b6b567d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mucus extraction<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Chest congestion<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-866c092 elementor-widget elementor-widget-text-editor\" data-id=\"866c092\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Effective removal of phlegm and chest congestion<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03015c6 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"03015c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-035ead0 elementor-widget elementor-widget-button\" data-id=\"035ead0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-wobble-horizontal\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7c9d6c5\" data-id=\"7c9d6c5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9949cd4 elementor-widget elementor-widget-image\" data-id=\"9949cd4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"760\" height=\"394\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-49-29.jpg\" class=\"attachment-large size-large wp-image-1823\" alt=\"\" srcset=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-49-29.jpg 760w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-49-29-300x156.jpg 300w\" sizes=\"(max-width: 760px) 100vw, 760px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a40d2c8 elementor-widget elementor-widget-spacer\" data-id=\"a40d2c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0799f67 elementor-widget elementor-widget-heading\" data-id=\"0799f67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Injection<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d853ccf elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d853ccf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Immunization<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Medication administration<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1f6f67 elementor-widget elementor-widget-text-editor\" data-id=\"e1f6f67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table><tbody><tr><td>Expert administration of immunizations and medications<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e6d040 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3e6d040\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1d2d01 elementor-widget elementor-widget-button\" data-id=\"d1d2d01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-wobble-horizontal\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-57eee69\" data-id=\"57eee69\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cde2803 elementor-widget elementor-widget-image\" data-id=\"cde2803\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"769\" height=\"1024\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-03-at-5.02.06-PM-769x1024.jpeg\" class=\"attachment-large size-large wp-image-1935\" alt=\"\" srcset=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-03-at-5.02.06-PM-769x1024.jpeg 769w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-03-at-5.02.06-PM-225x300.jpeg 225w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-03-at-5.02.06-PM-768x1023.jpeg 768w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/10\/WhatsApp-Image-2023-10-03-at-5.02.06-PM.jpeg 928w\" sizes=\"(max-width: 769px) 100vw, 769px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fa1d14 elementor-widget elementor-widget-spacer\" data-id=\"3fa1d14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3922199 elementor-widget elementor-widget-heading\" data-id=\"3922199\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Buka Buku Pink (Pregnancy Record)<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9dc0e73 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9dc0e73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pregnancy record book<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Maternity care<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d78b90e elementor-widget elementor-widget-text-editor\" data-id=\"d78b90e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"group w-full text-gray-800 dark:text-gray-100 border-b border-black\/10 dark:border-gray-900\/50 bg-gray-50 dark:bg-[#444654] sm:AIPRM__conversation__response\"><div class=\"flex p-4 gap-4 text-base md:gap-6 md:max-w-2xl lg:max-w-[38rem] xl:max-w-3xl md:py-6 lg:px-0 m-auto\"><div class=\"relative flex w-[calc(100%-50px)] flex-col gap-1 md:gap-3 lg:w-[calc(100%-115px)]\"><div class=\"flex flex-grow flex-col gap-3\"><div class=\"min-h-[20px] flex items-start overflow-x-auto whitespace-pre-wrap break-words flex-col gap-4\"><div class=\"markdown prose w-full break-words dark:prose-invert light AIPRM__conversation__response\"><table><tbody><tr><td>Opening the Pink Book for comprehensive maternity care<\/td><\/tr><\/tbody><\/table><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ddc406 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7ddc406\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84f30c5 elementor-widget elementor-widget-button\" data-id=\"84f30c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-wobble-horizontal\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-86d8e83 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86d8e83\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0e2dc4b\" data-id=\"0e2dc4b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c6949e5 elementor-widget elementor-widget-image\" data-id=\"c6949e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"340\" height=\"322\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/pf851-1.jpg\" class=\"attachment-large size-large wp-image-1827\" alt=\"\" srcset=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/pf851-1.jpg 340w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/pf851-1-300x284.jpg 300w\" sizes=\"(max-width: 340px) 100vw, 340px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eee0004 elementor-widget elementor-widget-spacer\" data-id=\"eee0004\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce7b25c elementor-widget elementor-widget-heading\" data-id=\"ce7b25c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Urine Pregnancy Test<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8c6bff elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d8c6bff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Pregnancy detection<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Personalised advice<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2521366 elementor-widget elementor-widget-text-editor\" data-id=\"2521366\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table><tbody><tr><td>Accurate urine-based pregnancy test results<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1583a7d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1583a7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-01b4b26 elementor-widget elementor-widget-button\" data-id=\"01b4b26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-wobble-horizontal\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7da8c19\" data-id=\"7da8c19\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f76fa69 elementor-widget elementor-widget-image\" data-id=\"f76fa69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"467\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/berkhatan.jpg\" class=\"attachment-large size-large wp-image-1826\" alt=\"\" srcset=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/berkhatan.jpg 700w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/berkhatan-300x200.jpg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d91c20 elementor-widget elementor-widget-spacer\" data-id=\"8d91c20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20544cb elementor-widget elementor-widget-heading\" data-id=\"20544cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Circumcision (Berkhatan)\t<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9fb30a elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f9fb30a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Male circumcision<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Surgical procedure<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f20ab65 elementor-widget elementor-widget-text-editor\" data-id=\"f20ab65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table><tbody><tr><td>Safe and professional male circumcision procedure<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0fed57 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b0fed57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b02275e elementor-widget elementor-widget-button\" data-id=\"b02275e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-wobble-horizontal\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-41ecf26\" data-id=\"41ecf26\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b85090 elementor-widget elementor-widget-image\" data-id=\"4b85090\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"736\" height=\"368\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-47-38.jpg\" class=\"attachment-large size-large wp-image-1825\" alt=\"\" srcset=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-47-38.jpg 736w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-47-38-300x150.jpg 300w\" sizes=\"(max-width: 736px) 100vw, 736px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9597893 elementor-widget elementor-widget-spacer\" data-id=\"9597893\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68856f6 elementor-widget elementor-widget-heading\" data-id=\"68856f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Suture<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dcc6724 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"dcc6724\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Wound closure<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Stitching<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72162d8 elementor-widget elementor-widget-text-editor\" data-id=\"72162d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table><tbody><tr><td>Skillful stitching for wound closure and proper healing<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40d5a3d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"40d5a3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5dd82ad elementor-widget elementor-widget-button\" data-id=\"5dd82ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-wobble-horizontal\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-88fddc6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"88fddc6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-446730b\" data-id=\"446730b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62a152f elementor-widget elementor-widget-image\" data-id=\"62a152f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"381\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/Minor-Surgery-1024x488-1.jpg\" class=\"attachment-large size-large wp-image-1824\" alt=\"\" srcset=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/Minor-Surgery-1024x488-1.jpg 1024w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/Minor-Surgery-1024x488-1-300x143.jpg 300w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/Minor-Surgery-1024x488-1-768x366.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3b4e7c elementor-widget elementor-widget-spacer\" data-id=\"c3b4e7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96fb4a6 elementor-widget elementor-widget-heading\" data-id=\"96fb4a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Minor Surgery<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06f51ea elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"06f51ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Surgical procedure<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Minor operation<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea88faf elementor-widget elementor-widget-text-editor\" data-id=\"ea88faf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table><tbody><tr><td>Skillful execution of minor surgical procedures<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77caa73 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"77caa73\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f5b0b6 elementor-widget elementor-widget-button\" data-id=\"2f5b0b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-wobble-horizontal\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d216a86\" data-id=\"d216a86\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e60e19 elementor-widget elementor-widget-image\" data-id=\"9e60e19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"798\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-41-31.jpg\" class=\"attachment-large size-large wp-image-1829\" alt=\"\" srcset=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-41-31.jpg 884w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-41-31-300x300.jpg 300w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-41-31-150x150.jpg 150w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-41-31-768x766.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b082fbf elementor-widget elementor-widget-spacer\" data-id=\"b082fbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45d308d elementor-widget elementor-widget-heading\" data-id=\"45d308d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Vaccination<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89a31cf elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"89a31cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Vaccination<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-hand-point-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Preventive care<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1ef8c5 elementor-widget elementor-widget-text-editor\" data-id=\"e1ef8c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<table><tbody><tr><td>Administering vaccines for preventive healthcare<\/td><\/tr><\/tbody><\/table>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed70110 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ed70110\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8021ba elementor-widget elementor-widget-button\" data-id=\"d8021ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-wobble-horizontal\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1626d16\" data-id=\"1626d16\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4fcd52b elementor-widget elementor-widget-image\" data-id=\"4fcd52b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-19_21-48-49-1024x684.jpg\" class=\"attachment-large size-large wp-image-1670\" alt=\"\" srcset=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-19_21-48-49-1024x684.jpg 1024w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-19_21-48-49-300x200.jpg 300w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-19_21-48-49-768x513.jpg 768w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-19_21-48-49.jpg 1426w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d244131 elementor-widget elementor-widget-spacer\" data-id=\"d244131\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4088a7b elementor-widget elementor-widget-heading\" data-id=\"4088a7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Other Services<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03a60b2 elementor-widget elementor-widget-text-editor\" data-id=\"03a60b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Looking for something else? Talk to us!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9737d1a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9737d1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ef6b97 elementor-widget elementor-widget-button\" data-id=\"2ef6b97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-wobble-horizontal\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4bed57a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4bed57a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca04ad8\" data-id=\"ca04ad8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ce5cbf elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7ce5cbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Our Business Value<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90a6124 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"90a6124\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Why Choose Us<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5d77df6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d77df6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3b493be elementor-invisible\" data-id=\"3b493be\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd3a37b ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"bd3a37b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text- icon-top-align elementor-animation-   \">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  \">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon icon icon-calendar1\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    5 Years Experience                <\/h3>\n                        \t\t  \t<p>Providing quality healthcare services with a decade of experience in the industry.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-eb996ad elementor-invisible\" data-id=\"eb996ad\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:400}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f7321f4 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"f7321f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text- icon-top-align elementor-animation-   \">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  \">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon icon icon-team\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Expert Team                <\/h3>\n                        \t\t  \t<p>A team of qualified experts dedicated to delivering exceptional care.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-69f588e elementor-invisible\" data-id=\"69f588e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:600}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5660c79 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"5660c79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text- icon-top-align elementor-animation-   \">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  \">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon fas fa-hand-holding-medical\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Patient-Centered Approach                <\/h3>\n                        \t\t  \t<p>Focusing on personalized care and attention to ensure patient satisfaction.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a12a0d3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a12a0d3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-fc207a1 elementor-invisible\" data-id=\"fc207a1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af0c4a0 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"af0c4a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text- icon-top-align elementor-animation-   \">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  \">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon icon icon-medicine\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Wide Range of Specialties                <\/h3>\n                        \t\t  \t<p>We offer a wide range of comprehensive healthcare services, catering to various medical needs. <\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6b939b7 elementor-invisible\" data-id=\"6b939b7\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:400}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57c6d52 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"57c6d52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text- icon-top-align elementor-animation-   \">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  \">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon fas fa-medkit\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    State-of-the-Art Facilities                <\/h3>\n                        \t\t  \t<p>Equipped with modern medical technology to deliver accurate diagnoses and effective treatments.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-3d78360 elementor-invisible\" data-id=\"3d78360\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:600}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9be20de ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"9be20de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-center text- icon-top-align elementor-animation-   \">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  \">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon icon icon-hand_shake\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    Trusted by 50+ Partners                <\/h3>\n                        \t\t  \t<p>Collaborating with a wide network of esteemed healthcare partners for seamless referrals and comprehensive care.<\/p>\n                                <\/div>\n        \n        \n                <\/div>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f173ce0 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"f173ce0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5795c7e\" data-id=\"5795c7e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f054fea elementor-widget elementor-widget-heading\" data-id=\"f054fea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Our Branches<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ab675d elementor-widget elementor-widget-heading\" data-id=\"4ab675d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Three Locations For your Convenience.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d2de66d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d2de66d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f1307ed elementor-invisible\" data-id=\"f1307ed\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-947b256 elementor-widget elementor-widget-image\" data-id=\"947b256\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/elementor\/thumbs\/Klinik-Ummah-Kota-Bharu-qajo7n59xinxiwdx2hkq1j23wh0thhr5b4x3p9w0u8.png\" title=\"Klinik Ummah Kota Bharu\" alt=\"Klinik Ummah Kota Bharu\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b4220fa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4220fa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2d48021\" data-id=\"2d48021\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf185ea elementor-widget elementor-widget-heading\" data-id=\"cf185ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Kota Bharu<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2d06a4 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c2d06a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Visit us<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bf72296 elementor-invisible\" data-id=\"bf72296\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c7052e elementor-widget elementor-widget-image\" data-id=\"0c7052e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/elementor\/thumbs\/WhatsApp-Image-2023-04-02-at-9.47.45-AM-1-qcg8bll1zoamcbyn1qgxujpqtz1dbyv2bhnrva7ha8.jpeg\" title=\"WhatsApp Image 2023-04-02 at 9.47.45 AM (1)\" alt=\"WhatsApp Image 2023-04-02 at 9.47.45 AM (1)\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-367e9d0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"367e9d0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f581299\" data-id=\"f581299\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-257d21c elementor-widget elementor-widget-heading\" data-id=\"257d21c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Kubang Kerian<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8350c2a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"8350c2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Visit us<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2444e90 elementor-invisible\" data-id=\"2444e90\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:400}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de8696f elementor-widget elementor-widget-image\" data-id=\"de8696f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/elementor\/thumbs\/Klinik-Ummah-Taman-Kurnia-Jaya-qajo7ct1uc9rz6sxqv3ts3o1d8fs4tm3lpqrf8bcqo.png\" title=\"Klinik Ummah Taman Kurnia Jaya\" alt=\"Klinik Ummah Taman Kurnia Jaya\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2a284fa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a284fa\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-85fccae\" data-id=\"85fccae\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f8ccd2 elementor-widget elementor-widget-heading\" data-id=\"3f8ccd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Taman Kurnia Jaya<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b6e886 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"8b6e886\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Visit us<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d0c0852 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d0c0852\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-32fafe7 elementor-invisible\" data-id=\"32fafe7\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed442c1 elementor-widget elementor-widget-image\" data-id=\"ed442c1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"516\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/08\/detail-of-handshake-of-doctor-and-patient-2021-08-27-17-17-24-utc-1024x661.jpg\" class=\"attachment-large size-large wp-image-1471\" alt=\"\" srcset=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/08\/detail-of-handshake-of-doctor-and-patient-2021-08-27-17-17-24-utc-1024x661.jpg 1024w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/08\/detail-of-handshake-of-doctor-and-patient-2021-08-27-17-17-24-utc-300x194.jpg 300w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/08\/detail-of-handshake-of-doctor-and-patient-2021-08-27-17-17-24-utc-768x496.jpg 768w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/08\/detail-of-handshake-of-doctor-and-patient-2021-08-27-17-17-24-utc-1536x992.jpg 1536w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/08\/detail-of-handshake-of-doctor-and-patient-2021-08-27-17-17-24-utc-2048x1323.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54afab1 elementor-widget elementor-widget-image\" data-id=\"54afab1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"528\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-54-05-1024x676.jpg\" class=\"attachment-large size-large wp-image-1822\" alt=\"\" srcset=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-54-05-1024x676.jpg 1024w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-54-05-300x198.jpg 300w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-54-05-768x507.jpg 768w, https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/09\/2023-09-30_16-54-05.jpg 1330w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9930644 elementor-invisible\" data-id=\"9930644\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d80238 elementor-widget elementor-widget-heading\" data-id=\"0d80238\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Testimonial<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7df9ac elementor-widget elementor-widget-heading\" data-id=\"f7df9ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hear From Our Satisfied Patients<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53f7bf5 elementor-widget elementor-widget-text-editor\" data-id=\"53f7bf5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad0e6dc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad0e6dc\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\"><div class=\"elementor-container elementor-column-gap-default\"><div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c371df\" data-id=\"c371df\" data-element_type=\"column\"><div class=\"elementor-widget-wrap elementor-element-populated e-swiper-container\"><div class=\"elementor-element elementor-element-969d306 elementor-widget elementor-widget-text-editor\" data-id=\"969d306\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><p>At Klinik Ummah, we are proud to have served numerous patients who have received exceptional care and attention from our dedicated medical professionals. We believe in putting our patients first, and it shows in the positive experiences they have had with us.<\/p><\/div><\/div><\/div><\/div><\/div><\/section>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f4c497 elementor-widget elementor-widget-shortcode\" data-id=\"1f4c497\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div class=\"wp-gr rpi wpac\" data-id=\"147\" data-layout=\"slider\" data-exec=\"false\" data-options='{&quot;text_size&quot;:&quot;&quot;,&quot;trans&quot;:{&quot;read more&quot;:&quot;read more&quot;}}'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" style=\"display:none!important\"><symbol id=\"grw-tripadvisor\" viewBox=\"0 0 713.496 713.496\"><g><circle fill=\"#34E0A1\" cx=\"356.749\" cy=\"356.748\" r=\"356.748\"\/><path d=\"M577.095,287.152l43.049-46.836h-95.465c-47.792-32.646-105.51-51.659-167.931-51.659   c-62.342,0-119.899,19.054-167.612,51.659H93.432l43.049,46.836c-26.387,24.075-42.929,58.754-42.929,97.259   c0,72.665,58.914,131.578,131.579,131.578c34.519,0,65.968-13.313,89.446-35.077l42.172,45.919l42.172-45.879   c23.478,21.764,54.887,35.037,89.406,35.037c72.665,0,131.658-58.913,131.658-131.578   C620.024,345.866,603.483,311.188,577.095,287.152z M225.17,473.458c-49.188,0-89.047-39.859-89.047-89.047   s39.86-89.048,89.047-89.048c49.187,0,89.047,39.86,89.047,89.048S274.357,473.458,225.17,473.458z M356.788,381.82   c0-58.595-42.61-108.898-98.853-130.383c30.413-12.716,63.776-19.771,98.813-19.771s68.439,7.055,98.853,19.771   C399.399,272.962,356.788,323.226,356.788,381.82z M488.367,473.458c-49.188,0-89.048-39.859-89.048-89.047   s39.86-89.048,89.048-89.048s89.047,39.86,89.047,89.048S537.554,473.458,488.367,473.458z M488.367,337.694   c-25.79,0-46.677,20.887-46.677,46.677c0,25.789,20.887,46.676,46.677,46.676c25.789,0,46.676-20.887,46.676-46.676   C535.042,358.621,514.156,337.694,488.367,337.694z M271.846,384.411c0,25.789-20.887,46.676-46.676,46.676   s-46.676-20.887-46.676-46.676c0-25.79,20.887-46.677,46.676-46.677C250.959,337.694,271.846,358.621,271.846,384.411z\"\/><\/g><\/symbol><symbol id=\"grw-google\" viewBox=\"0 0 512 512\"><g fill=\"none\" fill-rule=\"evenodd\"><path d=\"M482.56 261.36c0-16.73-1.5-32.83-4.29-48.27H256v91.29h127.01c-5.47 29.5-22.1 54.49-47.09 71.23v59.21h76.27c44.63-41.09 70.37-101.59 70.37-173.46z\" fill=\"#4285f4\"\/><path d=\"M256 492c63.72 0 117.14-21.13 156.19-57.18l-76.27-59.21c-21.13 14.16-48.17 22.53-79.92 22.53-61.47 0-113.49-41.51-132.05-97.3H45.1v61.15c38.83 77.13 118.64 130.01 210.9 130.01z\" fill=\"#34a853\"\/><path d=\"M123.95 300.84c-4.72-14.16-7.4-29.29-7.4-44.84s2.68-30.68 7.4-44.84V150.01H45.1C29.12 181.87 20 217.92 20 256c0 38.08 9.12 74.13 25.1 105.99l78.85-61.15z\" fill=\"#fbbc05\"\/><path d=\"M256 113.86c34.65 0 65.76 11.91 90.22 35.29l67.69-67.69C373.03 43.39 319.61 20 256 20c-92.25 0-172.07 52.89-210.9 130.01l78.85 61.15c18.56-55.78 70.59-97.3 132.05-97.3z\" fill=\"#ea4335\"\/><path d=\"M20 20h472v472H20V20z\"\/><\/g><\/symbol><\/svg><div class=\"grw-row grw-row-m\" data-options='{&quot;speed&quot;:3,&quot;autoplay&quot;:true,&quot;mousestop&quot;:true,&quot;breakpoints&quot;:&quot;&quot;}'><div class=\"grw-header\"><div class=\"grw-header-inner rpi-flx rpi-row12\"><div class=\"grw-img-wrap\"><img loading=\"lazy\" decoding=\"async\" class=\"grw-img\" src=\"https:\/\/lh3.googleusercontent.com\/places\/ANJU3DuR16CEOkhSYaUpkIpetaKhXcTsSROREA4JcNnNXQ533ulCdhZFt07JgAW8E_HhPIXgcyLYOvt6PGb65Xrjon4qLhewlYXBzLY=s1600-w300-h300\" loading=\"lazy\" alt=\"KLINIK UMMAH KOTA BHARU place picture\" width=\"50\" height=\"50\" onerror=\"if(this.src!='data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7')this.src='data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7';\" ><\/div><div class=\"rpi-flx rpi-col8\"><div class=\"wp-google-name\"><a href=\"https:\/\/maps.google.com\/?cid=14583260252941272513\" target=\"_blank\" rel=\"nofollow noopener\">KLINIK UMMAH KOTA BHARU<\/a><\/div><span class=\"rpi-stars\" style=\"--rating:5.0\">5.0<\/span><div class=\"wp-google-powered\" role=\"img\" aria-label=\"powered by Google\">powered by <span aria-hidden=\"true\"><span style=\"color:#3c6df0!important\">G<\/span><span style=\"color:#d93025!important\">o<\/span><span style=\"color:#fb8e28!important\">o<\/span><span style=\"color:#3c6df0!important\">g<\/span><span style=\"color:#188038!important\">l<\/span><span style=\"color:#d93025!important\">e<\/span><\/span><\/div><\/div><\/div><\/div><div class=\"rpi-slides-root grw-content\"><div class=\"grw-content-inner\"><button class=\"rpi-ltgt rpi-lt grw-prev\" tabindex=\"0\"><\/button><div class=\"rpi-slides grw-reviews rpi-slides-bite\" data-count=\"5\" data-offset=\"5\"><div class=\"rpi-slide grw-review\"><div class=\"rpi-flx rpi-col12 grw-review-inner grw-backgnd\"><div class=\"rpi-flx rpi-row12-center\"><div class=\"grw-img-wrap\"><img loading=\"lazy\" decoding=\"async\" class=\"grw-img\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/06\/ChIJAQsvPMyvtjERwUWjQ-8lYso_67a9de800a45881d667d45bf8ab7e66b.jpg\" loading=\"lazy\" alt=\"Nur Nazifah profile picture\" width=\"50\" height=\"50\" onerror=\"if(this.src!='https:\/\/ummahhealthcare.com.my\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png')this.src='https:\/\/ummahhealthcare.com.my\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png';\" ><\/div><div class=\"rpi-flx rpi-col6\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/111415354485412751017\/reviews\" class=\"wp-google-name\" target=\"_blank\" rel=\"nofollow noopener\">Nur Nazifah<\/a><div class=\"wp-google-time\" data-time=\"1683687241\">3 tahun yang lalu<\/div><\/div><\/div><span class=\"rpi-stars\" style=\"--rating:5\"><\/span><div class=\"rpi-flx rpi-col4\"><div class=\"wp-google-feedback grw-scroll\" ><span class=\"wp-google-text\">Alhamdulillah very satisfied. The service is all very good. The doctor and staff are very friendly and sporty &#x1f92d;. The clinic is spacious and comfortable. I really recommend it to anyone who wants to do treatment. I guarantee you will be satisfied&#x1f60a;&#x1f44d;. Thank you for the service provided. God willing, I will come again for another treatment. &#x1f609;&#x270c;&#xfe0f;<\/span><\/div><\/div><svg height=\"16\" width=\"16\" role=\"none\"><use href=\"#grw-google\"\/><\/svg><\/div><\/div><div class=\"rpi-slide grw-review\"><div class=\"rpi-flx rpi-col12 grw-review-inner grw-backgnd\"><div class=\"rpi-flx rpi-row12-center\"><div class=\"grw-img-wrap\"><img loading=\"lazy\" decoding=\"async\" class=\"grw-img\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/06\/ChIJAQsvPMyvtjERwUWjQ-8lYso_8ad97dcf09d17bb862a4cb4d24ee4618.jpg\" loading=\"lazy\" alt=\"Lock cafe Cafe profile picture\" width=\"50\" height=\"50\" onerror=\"if(this.src!='https:\/\/ummahhealthcare.com.my\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png')this.src='https:\/\/ummahhealthcare.com.my\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png';\" ><\/div><div class=\"rpi-flx rpi-col6\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/103032881824062424048\/reviews\" class=\"wp-google-name\" target=\"_blank\" rel=\"nofollow noopener\">Lock cafe Cafe<\/a><div class=\"wp-google-time\" data-time=\"1683522018\">3 tahun yang lalu<\/div><\/div><\/div><span class=\"rpi-stars\" style=\"--rating:5\"><\/span><div class=\"rpi-flx rpi-col4\"><div class=\"wp-google-feedback grw-scroll\" ><span class=\"wp-google-text\">Alhamdulillah, the doctor &amp; staff are very friendly and thorough. Received a free gift from my bby from the doctor.. INSHYAALLAH I will repeat this clinic..<\/span><\/div><\/div><svg height=\"16\" width=\"16\" role=\"none\"><use href=\"#grw-google\"\/><\/svg><\/div><\/div><div class=\"rpi-slide grw-review\"><div class=\"rpi-flx rpi-col12 grw-review-inner grw-backgnd\"><div class=\"rpi-flx rpi-row12-center\"><div class=\"grw-img-wrap\"><img loading=\"lazy\" decoding=\"async\" class=\"grw-img\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/06\/ChIJAQsvPMyvtjERwUWjQ-8lYso_8a59cc92c92efb231fdb7e7af79869f7.jpg\" loading=\"lazy\" alt=\"Che_Nur Syafiqah profile picture\" width=\"50\" height=\"50\" onerror=\"if(this.src!='https:\/\/ummahhealthcare.com.my\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png')this.src='https:\/\/ummahhealthcare.com.my\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png';\" ><\/div><div class=\"rpi-flx rpi-col6\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/104087123186681373370\/reviews\" class=\"wp-google-name\" target=\"_blank\" rel=\"nofollow noopener\">Che_Nur Syafiqah<\/a><div class=\"wp-google-time\" data-time=\"1682857767\">3 tahun yang lalu<\/div><\/div><\/div><span class=\"rpi-stars\" style=\"--rating:5\"><\/span><div class=\"rpi-flx rpi-col4\"><div class=\"wp-google-feedback grw-scroll\" ><span class=\"wp-google-text\">Today I had a scan, alhamdulillah, the doc and staff are all good, friendly.. the best service...<\/span><\/div><\/div><svg height=\"16\" width=\"16\" role=\"none\"><use href=\"#grw-google\"\/><\/svg><\/div><\/div><div class=\"rpi-slide grw-review\"><div class=\"rpi-flx rpi-col12 grw-review-inner grw-backgnd\"><div class=\"rpi-flx rpi-row12-center\"><div class=\"grw-img-wrap\"><img loading=\"lazy\" decoding=\"async\" class=\"grw-img\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/06\/ChIJAQsvPMyvtjERwUWjQ-8lYso_9a631e2e092694f80583f6b2784aff1d.jpg\" loading=\"lazy\" alt=\"Nur Athira profile picture\" width=\"50\" height=\"50\" onerror=\"if(this.src!='https:\/\/ummahhealthcare.com.my\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png')this.src='https:\/\/ummahhealthcare.com.my\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png';\" ><\/div><div class=\"rpi-flx rpi-col6\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/103054440717442737348\/reviews\" class=\"wp-google-name\" target=\"_blank\" rel=\"nofollow noopener\">Nur Athira<\/a><div class=\"wp-google-time\" data-time=\"1668247653\">4 tahun yang lalu<\/div><\/div><\/div><span class=\"rpi-stars\" style=\"--rating:5\"><\/span><div class=\"rpi-flx rpi-col4\"><div class=\"wp-google-feedback grw-scroll\" ><span class=\"wp-google-text\">I am very satisfied with the service of the doctor and staff at the clinic. . They are very friendly and customer friendly. . The atmosphere of the clinic is also very comfortable and the service is good. .&#x2b50;&#xfe0f;&#x2b50;&#xfe0f;&#x2b50;&#xfe0f;&#x2b50;&#xfe0f;&#x2b50;&#xfe0f;&#x2b50;&#xfe0f;<\/span><\/div><\/div><svg height=\"16\" width=\"16\" role=\"none\"><use href=\"#grw-google\"\/><\/svg><\/div><\/div><div class=\"rpi-slide grw-review\"><div class=\"rpi-flx rpi-col12 grw-review-inner grw-backgnd\"><div class=\"rpi-flx rpi-row12-center\"><div class=\"grw-img-wrap\"><img loading=\"lazy\" decoding=\"async\" class=\"grw-img\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/06\/ChIJAQsvPMyvtjERwUWjQ-8lYso_2db3142dbb7092bef366bee755ad18e1.jpg\" loading=\"lazy\" alt=\"Tej Naz profile picture\" width=\"50\" height=\"50\" onerror=\"if(this.src!='https:\/\/ummahhealthcare.com.my\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png')this.src='https:\/\/ummahhealthcare.com.my\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png';\" ><\/div><div class=\"rpi-flx rpi-col6\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/109102403290822420653\/reviews\" class=\"wp-google-name\" target=\"_blank\" rel=\"nofollow noopener\">Tej Naz<\/a><div class=\"wp-google-time\" data-time=\"1667875437\">4 tahun yang lalu<\/div><\/div><\/div><span class=\"rpi-stars\" style=\"--rating:5\"><\/span><div class=\"rpi-flx rpi-col4\"><div class=\"wp-google-feedback grw-scroll\" ><span class=\"wp-google-text\">Good service. The clinic is also beautiful.<\/span><\/div><\/div><svg height=\"16\" width=\"16\" role=\"none\"><use href=\"#grw-google\"\/><\/svg><\/div><\/div><\/div><button class=\"rpi-ltgt rpi-gt grw-next\" tabindex=\"0\"><\/button><div class=\"rpi-dots-wrap\"><div class=\"rpi-dots\"><\/div><\/div><\/div><\/div><\/div><script>(function(p){if(!p)return;let w=p.offsetWidth,m=function(a,b){return Math.min(a,b)===a};p.querySelector('.grw-row').classList.replace('grw-row-m','grw-row-'+(m(w,510)?'xs':m(w,750)?'x':m(w,1100)?'s':m(w,1450)?'m':m(w,1800)?'l':'xl'))})(document.currentScript?.parentElement)<\/script><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-288f118 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"288f118\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d34c477\" data-id=\"d34c477\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9543f4d elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"9543f4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Our Partners<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1be8d0b elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1be8d0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Trusted by more than 50 partners<br>for reliable healthcare support.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f4b6b8 elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"4f4b6b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;5&quot;,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/06\/COMPUMED-150x150.png\" alt=\"COMPUMED\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/06\/G-FLEX-150x150.png\" alt=\"G-FLEX\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/06\/MED-KAD-150x150.png\" alt=\"MED KAD\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/06\/MEDILINK-GLOBAL-150x150.png\" alt=\"MEDILINK GLOBAL\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/06\/MEDNEFITS-150x150.png\" alt=\"MEDNEFITS\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/06\/SEL-CARE-150x150.png\" alt=\"SEL CARE\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/06\/USM-KUBANG-KERIAN-150x150.png\" alt=\"USM KUBANG KERIAN\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/06\/WECARE-150x150.png\" alt=\"WECARE\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/06\/MYTPA-150x150.png\" alt=\"MYTPA\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ummahhealthcare.com.my\/wp-content\/uploads\/2023\/06\/AIA-150x150.png\" alt=\"AIA\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-579cea0 elementor-widget elementor-widget-text-editor\" data-id=\"579cea0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad0e6dc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad0e6dc\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\"><div class=\"elementor-container elementor-column-gap-default\"><div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c371df\" data-id=\"c371df\" data-element_type=\"column\"><div class=\"elementor-widget-wrap elementor-element-populated e-swiper-container\"><div class=\"elementor-element elementor-element-969d306 elementor-widget elementor-widget-text-editor\" data-id=\"969d306\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><p>Join the growing list of organizations that have partnered with us for their healthcare needs.<\/p><p>Discover the benefits of partnering with Ummah Healthcare Kelantan and unlock a range of quality healthcare services tailored to your needs.<\/p><\/div><\/div><\/div><\/div><\/div><\/section>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d38c9d9 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"d38c9d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xl\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Learn More<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Pith0s Treatments &amp; Procedures Service Treatments &#038; Procedures Nebulizer Inhalation therapy Respiratory care Effective respiratory treatment through inhalation therapy Learn More Dressing Wound care Bandage application Proper wound care through dressing and bandage application Learn More Ear Cleaning Ear wax removal Ear hygiene Thorough cleaning and removal of ear wax for ear hygiene Learn More&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":257,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-454","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/ummahhealthcare.com.my\/ms_my\/wp-json\/wp\/v2\/pages\/454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ummahhealthcare.com.my\/ms_my\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ummahhealthcare.com.my\/ms_my\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ummahhealthcare.com.my\/ms_my\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ummahhealthcare.com.my\/ms_my\/wp-json\/wp\/v2\/comments?post=454"}],"version-history":[{"count":67,"href":"https:\/\/ummahhealthcare.com.my\/ms_my\/wp-json\/wp\/v2\/pages\/454\/revisions"}],"predecessor-version":[{"id":2492,"href":"https:\/\/ummahhealthcare.com.my\/ms_my\/wp-json\/wp\/v2\/pages\/454\/revisions\/2492"}],"up":[{"embeddable":true,"href":"https:\/\/ummahhealthcare.com.my\/ms_my\/wp-json\/wp\/v2\/pages\/257"}],"wp:attachment":[{"href":"https:\/\/ummahhealthcare.com.my\/ms_my\/wp-json\/wp\/v2\/media?parent=454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}